{"id":135,"count":0,"description":"","link":"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/","name":"calli","slug":"calli-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>calli Archivi &#8212; Unlock Venice<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"calli Archivi &#8212; Unlock Venice\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Unlock Venice\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/06\/aiep-featured-195.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/tag\\\/calli-en\\\/\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/tag\\\/calli-en\\\/\",\"name\":\"calli Archivi &#8212; Unlock Venice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/tag\\\/calli-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/tag\\\/calli-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"calli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/\",\"name\":\"Unlock Venice\",\"description\":\"Venice Guide and Stays in Mestre\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#organization\"},\"alternateName\":\"Unlock Venice\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#organization\",\"name\":\"Unlock Venice\",\"alternateName\":\"U-Venice\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/unlock.png\",\"contentUrl\":\"https:\\\/\\\/www.unlockvenice.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/unlock.png\",\"width\":1254,\"height\":1254,\"caption\":\"Unlock Venice\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"calli Archivi &#8212; Unlock Venice","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"calli Archivi &#8212; Unlock Venice","og_url":"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/","og_site_name":"Unlock Venice","og_image":[{"width":1536,"height":1024,"url":"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/06\/aiep-featured-195.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/","url":"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/","name":"calli Archivi &#8212; Unlock Venice","isPartOf":{"@id":"https:\/\/www.unlockvenice.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unlockvenice.com\/en\/tag\/calli-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unlockvenice.com\/en\/"},{"@type":"ListItem","position":2,"name":"calli"}]},{"@type":"WebSite","@id":"https:\/\/www.unlockvenice.com\/en\/#website","url":"https:\/\/www.unlockvenice.com\/en\/","name":"Unlock Venice","description":"Venice Guide and Stays in Mestre","publisher":{"@id":"https:\/\/www.unlockvenice.com\/en\/#organization"},"alternateName":"Unlock Venice","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unlockvenice.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unlockvenice.com\/en\/#organization","name":"Unlock Venice","alternateName":"U-Venice","url":"https:\/\/www.unlockvenice.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unlockvenice.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/05\/unlock.png","contentUrl":"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/05\/unlock.png","width":1254,"height":1254,"caption":"Unlock Venice"},"image":{"@id":"https:\/\/www.unlockvenice.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/tags\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/posts?tags=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}