{"id":98,"count":0,"description":"","link":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/","name":"Arte e cultura","slug":"arte-e-cultura-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arte e cultura Archivi &#8212; Unlock Venice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arte e cultura Archivi &#8212; Unlock Venice\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Unlock Venice\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/06\/aiep-featured-195.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/category\\\/arte-e-cultura-en\\\/\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/category\\\/arte-e-cultura-en\\\/\",\"name\":\"Arte e cultura Archivi &#8212; Unlock Venice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/category\\\/arte-e-cultura-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/category\\\/arte-e-cultura-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte e cultura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/\",\"name\":\"Unlock Venice\",\"description\":\"Venice Guide and Stays in Mestre\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#organization\"},\"alternateName\":\"Unlock Venice\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#organization\",\"name\":\"Unlock Venice\",\"alternateName\":\"U-Venice\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unlockvenice.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/unlock.png\",\"contentUrl\":\"https:\\\/\\\/www.unlockvenice.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/unlock.png\",\"width\":1254,\"height\":1254,\"caption\":\"Unlock Venice\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unlockvenice.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arte e cultura Archivi &#8212; Unlock Venice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/","og_locale":"en_US","og_type":"article","og_title":"Arte e cultura Archivi &#8212; Unlock Venice","og_url":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/","og_site_name":"Unlock Venice","og_image":[{"width":1536,"height":1024,"url":"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/06\/aiep-featured-195.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/","url":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/","name":"Arte e cultura Archivi &#8212; Unlock Venice","isPartOf":{"@id":"https:\/\/www.unlockvenice.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unlockvenice.com\/en\/category\/arte-e-cultura-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unlockvenice.com\/en\/"},{"@type":"ListItem","position":2,"name":"Arte e cultura"}]},{"@type":"WebSite","@id":"https:\/\/www.unlockvenice.com\/en\/#website","url":"https:\/\/www.unlockvenice.com\/en\/","name":"Unlock Venice","description":"Venice Guide and Stays in Mestre","publisher":{"@id":"https:\/\/www.unlockvenice.com\/en\/#organization"},"alternateName":"Unlock Venice","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unlockvenice.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.unlockvenice.com\/en\/#organization","name":"Unlock Venice","alternateName":"U-Venice","url":"https:\/\/www.unlockvenice.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.unlockvenice.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/05\/unlock.png","contentUrl":"https:\/\/www.unlockvenice.com\/wp-content\/uploads\/2026\/05\/unlock.png","width":1254,"height":1254,"caption":"Unlock Venice"},"image":{"@id":"https:\/\/www.unlockvenice.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/categories\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.unlockvenice.com\/en\/wp-json\/wp\/v2\/posts?categories=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}